{"id":5472,"date":"2025-07-04T13:47:40","date_gmt":"2025-07-04T11:47:40","guid":{"rendered":"https:\/\/blog.activetravel.com.tn\/?p=5472"},"modified":"2025-07-04T13:51:19","modified_gmt":"2025-07-04T11:51:19","slug":"panda-geant","status":"publish","type":"post","link":"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/","title":{"rendered":"PANDA GEANT"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"5472\" class=\"elementor elementor-5472\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4a7731 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4a7731\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-cf53cd0\" data-id=\"cf53cd0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d5f3415 elementor-widget elementor-widget-image\" data-id=\"d5f3415\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 13-09-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"573\" src=\"https:\/\/blog.activetravel.com.tn\/wp-content\/uploads\/2025\/07\/panda1.jpg\" class=\"attachment-large size-large wp-image-5476\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-5200532\" data-id=\"5200532\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11d83ab elementor-widget elementor-widget-image\" data-id=\"11d83ab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"573\" src=\"https:\/\/blog.activetravel.com.tn\/wp-content\/uploads\/2025\/07\/panda2.jpg\" class=\"attachment-large size-large wp-image-5477\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-18a9e25\" data-id=\"18a9e25\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bb44e07 elementor-widget elementor-widget-image\" data-id=\"bb44e07\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"860\" height=\"573\" src=\"https:\/\/blog.activetravel.com.tn\/wp-content\/uploads\/2025\/07\/pandz3.jpg\" class=\"attachment-large size-large wp-image-5478\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d1c998 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d1c998\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ab21432\" data-id=\"ab21432\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-242c615 elementor-widget elementor-widget-text-editor\" data-id=\"242c615\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 13-09-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Nom Scientifique\u00a0: Ailuropoda melanoleuca<\/p><p>En chinois\u00a0: da xiongmao (grand chat ours)<\/p><p>Le panda est class\u00e9 parmi les mammif\u00e8res, famille des Ursid\u00e9s.<\/p><p>C\u2019est un carnivore, il poss\u00e8de 42 dents avec des molaires plates et larges sp\u00e9cifiques \u00e0 son r\u00e9gime alimentaire.<\/p><p>Son poids varie de 80 \u00e0 125 kg, le poids du male \u00e9tant sup\u00e9rieur \u00e0 celui de la femelle.<\/p><p>Il a une taille de 1,5 \u00e0 1,8 m\u00e8tres.<\/p><p>Sa robe est faite d\u2019une fourrure blanche avec une couleur noire au niveau des pattes, des oreilles et au contour des yeux.<\/p><p>Son ou\u00efe et son odorat sont tr\u00e8s fins contrairement \u00e0 sa vue qui est m\u00e9diocre.<\/p><p>Son alimentation est \u00e0 99 % \u00e0 base de pousses et de feuilles de bambou. Etant donn\u00e9 que le bambou est pauvre en nutriments, le panda doit en manger beaucoup (20 kg par jour) avec des cycles de 3-4 heures de repas et 2-3 heures de sommeil. Occasionnellement, il mange des \u0153ufs, des insectes et des petits rongeurs. Sa main poss\u00e8de un faux pousse (6 doigts) adapt\u00e9 \u00e0 son alimentation en l\u2019aidant \u00e0 attraper les tiges de bambou.<\/p><p>Chez le panda, la maturit\u00e9 sexuelle est atteinte \u00e0 l\u2019\u00e2ge de 5-6 ans. Le cycle sexuel ne dure que quelques jours par an, d\u2019o\u00f9 une faible f\u00e9condit\u00e9 et une reproduction difficile. La dur\u00e9e de gestation est de 4-5 mois avec 1 \u00e0 3 petits par port\u00e9e. La m\u00e8re n\u2019en \u00e9l\u00e8ve qu\u2019un seul ! Le nouveau-n\u00e9 ne p\u00e8se que 90 \u00e0 140 grammes. Il est de couleur rose, aveugle et sans fourrure. Le sevrage est \u00e0 10 mois mais le petit ne sera totalement libre qu\u2019\u00e0 l\u2019\u00e2ge de 18 mois. L\u2019esp\u00e9rance de vie est estim\u00e9e \u00e0 20-25 ans.<\/p><p>Le panda est end\u00e9mique (pr\u00e9sence naturelle exclusive) de la Chine sud centrale\u00a0: forets d\u2019altitude 1 \u00e0 4 milles m\u00e8tres o\u00f9 dominent les bambous. On estime une population de deux milles pandas \u00e0 l\u2019\u00e9tat sauvage. 600 pandas sont h\u00e9berg\u00e9s dans 26 r\u00e9serves chinoises. 50 pandas sont log\u00e9s dans des zoos dans le monde. Depuis1984, le gouvernement chinois loue \u00e0 un prix \u00e9lev\u00e9 les pandas \u00e0 des zoos (un million de dollars par an).<\/p><p>L\u2019esp\u00e8ce est consid\u00e9r\u00e9e menac\u00e9e \u00e0 cause de la d\u00e9forestation, le manque de for\u00eats de bambou et l\u2019urbanisme croissant.<\/p><p>Les seuls pr\u00e9dateurs naturels des pandas sont le l\u00e9opard des neiges et les chacals. En Chine, tuer un panda est passible de peine de mort, remplac\u00e9e en 2010 par la prison.<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-11f90a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"11f90a6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0f3f892\" data-id=\"0f3f892\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db11b8f elementor-widget elementor-widget-text-editor\" data-id=\"db11b8f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p>Dr Habib BOUAOUINA<\/p><p>V\u00e9t\u00e9rinaire Biologiste<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Nom Scientifique\u00a0: Ailuropoda melanoleuca En chinois\u00a0: da xiongmao (grand chat ours) Le panda est class\u00e9 parmi les mammif\u00e8res, famille des Ursid\u00e9s. C\u2019est un carnivore, il poss\u00e8de 42 dents avec des molaires plates et larges sp\u00e9cifiques \u00e0 son r\u00e9gime alimentaire. Son poids varie de 80 \u00e0 125 kg, le poids du male \u00e9tant sup\u00e9rieur \u00e0 celui [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":5478,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[61],"tags":[],"class_list":["post-5472","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecologie-et-solidarite"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PANDA GEANT - Blog activetravel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PANDA GEANT - Blog activetravel\" \/>\n<meta property=\"og:description\" content=\"Nom Scientifique\u00a0: Ailuropoda melanoleuca En chinois\u00a0: da xiongmao (grand chat ours) Le panda est class\u00e9 parmi les mammif\u00e8res, famille des Ursid\u00e9s. C\u2019est un carnivore, il poss\u00e8de 42 dents avec des molaires plates et larges sp\u00e9cifiques \u00e0 son r\u00e9gime alimentaire. Son poids varie de 80 \u00e0 125 kg, le poids du male \u00e9tant sup\u00e9rieur \u00e0 celui [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog activetravel\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-04T11:47:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-04T11:51:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.activetravel.com.tn\/wp-content\/uploads\/2025\/07\/pandz3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user-activetravel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"user-activetravel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/\",\"url\":\"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/\",\"name\":\"PANDA GEANT - Blog activetravel\",\"isPartOf\":{\"@id\":\"https:\/\/blog.activetravel.com.tn\/#website\"},\"datePublished\":\"2025-07-04T11:47:40+00:00\",\"dateModified\":\"2025-07-04T11:51:19+00:00\",\"author\":{\"@id\":\"https:\/\/blog.activetravel.com.tn\/#\/schema\/person\/efed5c7d1e7a3d6a9f27c0064001a4ab\"},\"breadcrumb\":{\"@id\":\"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/blog.activetravel.com.tn\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PANDA GEANT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/blog.activetravel.com.tn\/#website\",\"url\":\"https:\/\/blog.activetravel.com.tn\/\",\"name\":\"Blog activetravel\",\"description\":\"Agence de voyage Tunisie : R\u00e9servation h\u00f4tels chez Active Travel, la meilleure agence de voyages Tunisie.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/blog.activetravel.com.tn\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/blog.activetravel.com.tn\/#\/schema\/person\/efed5c7d1e7a3d6a9f27c0064001a4ab\",\"name\":\"user-activetravel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/blog.activetravel.com.tn\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d4ee43dc1dac7aa76aa54a064263112143b452b30faa743c9e6b972f4d6be826?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d4ee43dc1dac7aa76aa54a064263112143b452b30faa743c9e6b972f4d6be826?s=96&d=mm&r=g\",\"caption\":\"user-activetravel\"},\"url\":\"https:\/\/blog.activetravel.com.tn\/index.php\/author\/user-activetravel\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PANDA GEANT - Blog activetravel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/","og_locale":"fr_FR","og_type":"article","og_title":"PANDA GEANT - Blog activetravel","og_description":"Nom Scientifique\u00a0: Ailuropoda melanoleuca En chinois\u00a0: da xiongmao (grand chat ours) Le panda est class\u00e9 parmi les mammif\u00e8res, famille des Ursid\u00e9s. C\u2019est un carnivore, il poss\u00e8de 42 dents avec des molaires plates et larges sp\u00e9cifiques \u00e0 son r\u00e9gime alimentaire. Son poids varie de 80 \u00e0 125 kg, le poids du male \u00e9tant sup\u00e9rieur \u00e0 celui [&hellip;]","og_url":"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/","og_site_name":"Blog activetravel","article_published_time":"2025-07-04T11:47:40+00:00","article_modified_time":"2025-07-04T11:51:19+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/blog.activetravel.com.tn\/wp-content\/uploads\/2025\/07\/pandz3.jpg","type":"image\/jpeg"}],"author":"user-activetravel","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"user-activetravel","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/","url":"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/","name":"PANDA GEANT - Blog activetravel","isPartOf":{"@id":"https:\/\/blog.activetravel.com.tn\/#website"},"datePublished":"2025-07-04T11:47:40+00:00","dateModified":"2025-07-04T11:51:19+00:00","author":{"@id":"https:\/\/blog.activetravel.com.tn\/#\/schema\/person\/efed5c7d1e7a3d6a9f27c0064001a4ab"},"breadcrumb":{"@id":"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/blog.activetravel.com.tn\/index.php\/2025\/07\/04\/panda-geant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/blog.activetravel.com.tn\/"},{"@type":"ListItem","position":2,"name":"PANDA GEANT"}]},{"@type":"WebSite","@id":"https:\/\/blog.activetravel.com.tn\/#website","url":"https:\/\/blog.activetravel.com.tn\/","name":"Blog activetravel","description":"Agence de voyage Tunisie : R\u00e9servation h\u00f4tels chez Active Travel, la meilleure agence de voyages Tunisie.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.activetravel.com.tn\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/blog.activetravel.com.tn\/#\/schema\/person\/efed5c7d1e7a3d6a9f27c0064001a4ab","name":"user-activetravel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/blog.activetravel.com.tn\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d4ee43dc1dac7aa76aa54a064263112143b452b30faa743c9e6b972f4d6be826?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4ee43dc1dac7aa76aa54a064263112143b452b30faa743c9e6b972f4d6be826?s=96&d=mm&r=g","caption":"user-activetravel"},"url":"https:\/\/blog.activetravel.com.tn\/index.php\/author\/user-activetravel\/"}]}},"jetpack_featured_media_url":"https:\/\/blog.activetravel.com.tn\/wp-content\/uploads\/2025\/07\/pandz3.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/blog.activetravel.com.tn\/index.php\/wp-json\/wp\/v2\/posts\/5472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.activetravel.com.tn\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.activetravel.com.tn\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.activetravel.com.tn\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.activetravel.com.tn\/index.php\/wp-json\/wp\/v2\/comments?post=5472"}],"version-history":[{"count":7,"href":"https:\/\/blog.activetravel.com.tn\/index.php\/wp-json\/wp\/v2\/posts\/5472\/revisions"}],"predecessor-version":[{"id":5482,"href":"https:\/\/blog.activetravel.com.tn\/index.php\/wp-json\/wp\/v2\/posts\/5472\/revisions\/5482"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.activetravel.com.tn\/index.php\/wp-json\/wp\/v2\/media\/5478"}],"wp:attachment":[{"href":"https:\/\/blog.activetravel.com.tn\/index.php\/wp-json\/wp\/v2\/media?parent=5472"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.activetravel.com.tn\/index.php\/wp-json\/wp\/v2\/categories?post=5472"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.activetravel.com.tn\/index.php\/wp-json\/wp\/v2\/tags?post=5472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}